{"id":1,"count":29,"description":"Accessories, wigs, jewelry, costume props, gloves, hats, shoes, stockings, corsets, necklaces,  and more.","link":"http:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/","name":"Accessories","slug":"accessories","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accessories Archives - Sexy 2 Scary Adult Halloween Costume Ideas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accessories Archives - Sexy 2 Scary Adult Halloween Costume Ideas\" \/>\n<meta property=\"og:description\" content=\"Accessories, wigs, jewelry, costume props, gloves, hats, shoes, stockings, corsets, necklaces, and more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/\" \/>\n<meta property=\"og:site_name\" content=\"Sexy 2 Scary Adult Halloween Costume Ideas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/category\\\/accessories\\\/\",\"url\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/category\\\/accessories\\\/\",\"name\":\"Accessories Archives - Sexy 2 Scary Adult Halloween Costume Ideas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/category\\\/accessories\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/category\\\/accessories\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accessories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/#website\",\"url\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/\",\"name\":\"Sexy 2 Scary Adult Halloween Costume Ideas\",\"description\":\"Great Adult Costumes &amp; Ideas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/doodlenut.com\\\/adulthalloween\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accessories Archives - Sexy 2 Scary Adult Halloween Costume Ideas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/","og_locale":"en_US","og_type":"article","og_title":"Accessories Archives - Sexy 2 Scary Adult Halloween Costume Ideas","og_description":"Accessories, wigs, jewelry, costume props, gloves, hats, shoes, stockings, corsets, necklaces, and more.","og_url":"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/","og_site_name":"Sexy 2 Scary Adult Halloween Costume Ideas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/","url":"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/","name":"Accessories Archives - Sexy 2 Scary Adult Halloween Costume Ideas","isPartOf":{"@id":"https:\/\/doodlenut.com\/adulthalloween\/#website"},"breadcrumb":{"@id":"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/doodlenut.com\/adulthalloween\/category\/accessories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/doodlenut.com\/adulthalloween\/"},{"@type":"ListItem","position":2,"name":"Accessories"}]},{"@type":"WebSite","@id":"https:\/\/doodlenut.com\/adulthalloween\/#website","url":"https:\/\/doodlenut.com\/adulthalloween\/","name":"Sexy 2 Scary Adult Halloween Costume Ideas","description":"Great Adult Costumes &amp; Ideas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/doodlenut.com\/adulthalloween\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/doodlenut.com\/adulthalloween\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/doodlenut.com\/adulthalloween\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/doodlenut.com\/adulthalloween\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/doodlenut.com\/adulthalloween\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}