{"id":52,"count":22,"description":"Blue - neon Blue- bright Blue- dark Blue - If it's got BLue on it - then we'll pull it up for you.","link":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/","name":"Blue","slug":"blue-color","taxonomy":"category","parent":3,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blue Archives - CooL Outdoor Toys for Kids &amp; Adults!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blue Archives - CooL Outdoor Toys for Kids &amp; Adults!\" \/>\n<meta property=\"og:description\" content=\"Blue &#8211; neon Blue- bright Blue- dark Blue &#8211; If it&#8217;s got BLue on it &#8211; then we&#8217;ll pull it up for you.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/\" \/>\n<meta property=\"og:site_name\" content=\"CooL Outdoor Toys for Kids &amp; Adults!\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/category\\\/color\\\/blue-color\\\/\",\"url\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/category\\\/color\\\/blue-color\\\/\",\"name\":\"Blue Archives - CooL Outdoor Toys for Kids &amp; Adults!\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/category\\\/color\\\/blue-color\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/category\\\/color\\\/blue-color\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Color\",\"item\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/category\\\/color\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blue\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/#website\",\"url\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/\",\"name\":\"CooL Outdoor Toys for Kids &amp; Adults!\",\"description\":\"Toys to blow your mind\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/doodlenut.com\\\/extremetoys\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blue Archives - CooL Outdoor Toys for Kids &amp; Adults!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/","og_locale":"en_US","og_type":"article","og_title":"Blue Archives - CooL Outdoor Toys for Kids &amp; Adults!","og_description":"Blue &#8211; neon Blue- bright Blue- dark Blue &#8211; If it&#8217;s got BLue on it &#8211; then we&#8217;ll pull it up for you.","og_url":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/","og_site_name":"CooL Outdoor Toys for Kids &amp; Adults!","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/","url":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/","name":"Blue Archives - CooL Outdoor Toys for Kids &amp; Adults!","isPartOf":{"@id":"http:\/\/doodlenut.com\/extremetoys\/#website"},"breadcrumb":{"@id":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/blue-color\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/doodlenut.com\/extremetoys\/"},{"@type":"ListItem","position":2,"name":"Color","item":"http:\/\/doodlenut.com\/extremetoys\/category\/color\/"},{"@type":"ListItem","position":3,"name":"Blue"}]},{"@type":"WebSite","@id":"http:\/\/doodlenut.com\/extremetoys\/#website","url":"http:\/\/doodlenut.com\/extremetoys\/","name":"CooL Outdoor Toys for Kids &amp; Adults!","description":"Toys to blow your mind","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/doodlenut.com\/extremetoys\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/doodlenut.com\/extremetoys\/wp-json\/wp\/v2\/categories\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/doodlenut.com\/extremetoys\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/doodlenut.com\/extremetoys\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/doodlenut.com\/extremetoys\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"http:\/\/doodlenut.com\/extremetoys\/wp-json\/wp\/v2\/posts?categories=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}